{"id":7965,"date":"2025-10-29T13:48:00","date_gmt":"2025-10-29T13:48:00","guid":{"rendered":"https:\/\/ortodonciabarcelona.com\/blog\/?p=7965"},"modified":"2025-11-07T13:49:23","modified_gmt":"2025-11-07T13:49:23","slug":"cuantos-dientes-tenemos","status":"publish","type":"post","link":"https:\/\/ortodonciabarcelona.com\/blog\/cuantos-dientes-tenemos\/","title":{"rendered":"\u00bfCu\u00e1ntos dientes tenemos?"},"content":{"rendered":"\r\n<p>Seguro que alguna vez te lo has planteado: \u00bftenemos el mismo n\u00famero de dientes de ni\u00f1os que de adultos?, \u00bftiene todo el mundo igual cantidad de piezas?, \u00bfqu\u00e9 funciones cumplen unos dientes y otros?<\/p>\r\n\r\n\r\n\r\n<p>En realidad, son cuestiones sencillas pero que nos incitan a vigilar nuestra salud y la de los nuestros, as\u00ed que desde <b><a href=\"https:\/\/ortodonciabarcelona.com\/\" target=\"_blank\" rel=\"noopener\">Ortodoncia Barcelona<\/a> Tres Torres<\/b>, hoy vamos a aclarar tus dudas y a indagar un poco m\u00e1s all\u00e1: adem\u00e1s de ver cu\u00e1ntos dientes tenemos ahondaremos en cu\u00e1les son los problemas m\u00e1s comunes con los dientes y cu\u00e1l es la forma de tratarlos.<\/p>\r\n\r\n\r\n\r\n<p>Y recuerda, la prevenci\u00f3n es la t\u00e9cnica m\u00e1s efectiva, hay que trabajar por una sonrisa sana y feliz desde la infancia. Veamos qu\u00e9 herramientas nos da la naturaleza para empezar.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><strong>\u00bfCu\u00e1ntos dientes de leche tenemos?<\/strong><\/h2>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/dientes-de-leche.jpg\"><img decoding=\"async\" width=\"700\" height=\"379\" class=\"lazyload wp-image-7970\" src=\"https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/dientes-de-leche.jpg\" data-orig-src=\"https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/dientes-de-leche.jpg\" alt=\"Imagen boca infantil mostrando dientes de leche\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27700%27%20height%3D%27379%27%20viewBox%3D%270%200%20700%20379%27%3E%3Crect%20width%3D%27700%27%20height%3D%27379%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/dientes-de-leche-200x108.jpg 200w, https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/dientes-de-leche-300x162.jpg 300w, https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/dientes-de-leche-400x217.jpg 400w, https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/dientes-de-leche-600x325.jpg 600w, https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/dientes-de-leche.jpg 700w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<p>Los famosos dientes de leche, que luego cambiaremos por la dentici\u00f3n definitiva, <strong>aparecen durante el primer a\u00f1o de vida<\/strong>, como norma general. El \u00abesperado\u00bb primer diente suele hacer su aparici\u00f3n cuando el beb\u00e9 cuenta con unos 6 meses de edad.<\/p>\r\n\r\n\r\n\r\n<p>A partir de ese momento, comienza <strong>un proceso que durar\u00e1 aproximadamente hasta los 3 a\u00f1os<\/strong>, durante el cual ir\u00e1n apareciendo todas estas peque\u00f1as y preciadas piezas, hasta completar los 20 dientes de leche que componen la dentici\u00f3n temporal: 8 incisivos, 4 caninos y 8 molares.<\/p>\r\n\r\n\r\n\r\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\r\n<p><strong>CONSEJO ORTODONCIA TRES TORRES<\/strong>: estos plazos de los que hablamos son siempre orientativos. Si tu beb\u00e9 lleva otro ritmo, simplemente cons\u00faltanos, se puede hacer un seguimiento de la salud dental desde el primer a\u00f1o de vida.\u00a0\u00a0<\/p>\r\n<\/blockquote>\r\n\r\n\r\n\r\n<p>Adem\u00e1s de cu\u00e1ntos dientes de leche tenemos, es com\u00fan preguntarse \u00bfcu\u00e1ndo se empieza a ver una transformaci\u00f3n? Entre los 6 y los 12 a\u00f1os de edad, comienza la dentici\u00f3n mixta, esa \u00abentretenida\u00bb etapa en la que conviven piezas de leche y piezas definitivas.<\/p>\r\n\r\n\r\n\r\n<p>Importante, no lo olvides, pr\u00e1cticamente desde el primer a\u00f1o de vida va a ser fundamental no desatender el cuidado de los dientes de leche. Ten en cuenta que las estructuras orales est\u00e1n creciendo y poniendo la base para una futura sonrisa feliz.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><strong>\u00bfCu\u00e1ntos dientes tiene un adulto?<\/strong><\/h2>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/dientes-adulto.jpg\"><img decoding=\"async\" width=\"700\" height=\"467\" class=\"lazyload wp-image-7974\" src=\"https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/dientes-adulto.jpg\" data-orig-src=\"https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/dientes-adulto.jpg\" alt=\"Imagen boca adulto mostrando dientes\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27700%27%20height%3D%27467%27%20viewBox%3D%270%200%20700%20467%27%3E%3Crect%20width%3D%27700%27%20height%3D%27467%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/dientes-adulto-200x133.jpg 200w, https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/dientes-adulto-300x200.jpg 300w, https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/dientes-adulto-400x267.jpg 400w, https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/dientes-adulto-600x400.jpg 600w, https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/dientes-adulto.jpg 700w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<p>Algunos antes, otros despu\u00e9s, m\u00e1s o menos a los 12 a\u00f1os, los ni\u00f1os ya cuentan con la dentici\u00f3n definitiva en sus bocas.<\/p>\r\n\r\n\r\n\r\n<p>Sin embargo, y a pesar de que ante la cuesti\u00f3n de cu\u00e1ntos dientes tenemos los humanos, <strong>todos deber\u00edamos disponer de 32 piezas permanentes<\/strong>, esto no siempre es as\u00ed. Es posible que alguna pieza no erupcione como debe, que tus cordales no hagan aparici\u00f3n o que, por el contrario, cuentes con un diente supernumerario que rompa el esquema num\u00e9rico de una dentici\u00f3n normal.<\/p>\r\n\r\n\r\n\r\n<p><strong>Muchos factores, adem\u00e1s de los gen\u00e9ticos, pueden ser los causantes de la p\u00e9rdida de alguna pieza<\/strong>, desde malos h\u00e1bitos a un d\u00e9ficit de la higiene bucodental. Afortunadamente, muchos de estos problemas son subsanables con las nuevas t\u00e9cnicas de implantolog\u00eda y ortodoncia.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><strong>Funci\u00f3n de los dientes<\/strong><\/h2>\r\n\r\n\r\n\r\n<p>Bien, llegados a este punto, sabemos con qu\u00e9 n\u00famero de piezas contamos (o deber\u00edamos contar), pero \u00bfqu\u00e9 papel realiza cada una? Y no s\u00f3lo hablamos de su lugar en nuestra sonrisa, sobre todo hablamos de funcionalidad o funci\u00f3n de los dientes.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><strong>Tipos de dientes en adultos<\/strong><\/h2>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li><strong>Incisivos<\/strong>: los incisivos son las piezas que nos permiten morder y se encargan de cortar la comida. Son planos y delgados y presentan diferente anchura, seg\u00fan el papel que desarrollan. Disponemos en total de 8 incisivos, 4 en cada una de las arcadas.<\/li>\r\n<li><strong>Caninos<\/strong>: estos dientes, aunque no lo parezca, cumplen un cometido importante a la hora de comer, hablar o mantener la forma de los labios. De hecho, tambi\u00e9n gu\u00edan la posici\u00f3n de los dientes restantes. Te ayudan a cortar y rasgar los alimentos en trozos m\u00e1s peque\u00f1os, pero tambi\u00e9n trabajan junto con los incisivos para formar las palabras. Contamos con 4 caninos.<\/li>\r\n<li><strong>Premolares<\/strong>: a diferencia de los incisivos y los caninos, los premolares ofrecen una superficie de mordida plana. Sirven para desgarrar y triturar los alimentos. Disponemos de 8 premolares.<\/li>\r\n<li><strong>Molares<\/strong>: son los dientes m\u00e1s grandes y fuertes de nuestra boca. Su funci\u00f3n es masticar, triturar y moler los alimentos. En total, contamos con 12 piezas, incluyendo las cordales. Estas \u00faltimas suelen salir a partir de los 18 a\u00f1os de edad, si bien hay personas que no las tienen y, de hecho, han dejado de cumplir una funci\u00f3n en nuestras arcadas. \u00a0<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><strong>Principales problemas de los dientes<\/strong><\/h2>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li><strong>Dientes de leche<\/strong>: es habitual pensar que no hace falta dedicarles mucha atenci\u00f3n a los dientes de leche, ya que ser\u00e1n sustituidos por otras piezas de dentici\u00f3n en el futuro. Sin embargo, esto es un error. Son la base de una futura boca sana. Cuatro recomendaciones:\r\n<ul>\r\n<li>Cepillarlos dos veces al d\u00eda con crema fluorada infantil.<\/li>\r\n<\/ul>\r\n<ul>\r\n<li>Visitar al odontopediatra con regularidad.<\/li>\r\n<\/ul>\r\n<ul>\r\n<li>A los 6 a\u00f1os realizar una visita al ortodoncista ya que es cuando los primeros molares definitivos erupcionan. <a href=\"https:\/\/www.ortodonciabarcelona.com\/edades\/ninos\/\">Saber m\u00e1s sobre ortodoncia preventiva en ni\u00f1os.<\/a><\/li>\r\n<\/ul>\r\n<ul>\r\n<li>Y algo si cabe m\u00e1s importante: vigilar la dieta de los peque\u00f1os para que sea lo m\u00e1s sana posible.<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li><strong>Dientes definitivo<\/strong>s: adem\u00e1s de las caries provocadas por la acci\u00f3n de las bacterias existentes en la boca, y de otros problemas que pueden ocasionarse por una higiene deficiente de enc\u00edas y piezas dentales (periodontitis, halitosis, etc.), un problema muy com\u00fan es el api\u00f1amiento de los dientes:\r\n<ul>\r\n<li>Es habitual en <strong>adultos j\u00f3venes y adultos en general el api\u00f1amiento terciario<\/strong>. Consiste en que los incisivos inferiores tienden a api\u00f1arse provocando una gran acumulaci\u00f3n de placa y, por consiguiente, m\u00e1s p\u00e9rdida de hueso entre las piezas, al no poder aplicar una limpieza adecuada.<\/li>\r\n<\/ul>\r\n<ul>\r\n<li>El <a href=\"https:\/\/ortodonciabarcelona.com\/blog\/dientes-apinados-como-la-ortodoncia-puede-ayudarte\/\">\u00fanico tratamiento<\/a> que tiene un problema de estas caracter\u00edsticas es la <strong>ortodoncia<\/strong>. De hecho, el api\u00f1amiento dental debe tratarse cuanto antes, ya que con los a\u00f1os el tama\u00f1o del hueso disminuye y los dientes se api\u00f1an cada vez m\u00e1s.<\/li>\r\n<\/ul>\r\n<ul>\r\n<li>Existen distintos tratamientos de ortodoncia: brackets met\u00e1licos, brackets de zafiro, ortodoncia lingual y <a href=\"https:\/\/www.ortodonciabarcelona.com\/tipos-de-ortodoncia\/invisalign\/\">ortodoncia invisible<\/a>, una opci\u00f3n altamente recomendable que te ofrecemos como especialistas de Invisalign en Barcelona.<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<p>Para concertar una visita preventiva cuando tu hij@ cumpla los 6 a\u00f1os, o si tienes un problema en tus dientes que crees pudiera tratarse con ortodoncia, puedes pedir cita ahora con nuestros especialistas en\u00a0<strong>ortodoncia en Barcelona<\/strong>, el Dr. Fernando de la Iglesia o el Dr. Oriol Quevedo, llamando al 934 142 312. \u00a1La primera visita es gratuita!\u00a0<\/p>\r\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;7965&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;3&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;2.7&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Punt\u00faa este post&quot;,&quot;legend&quot;:&quot;2.7\\\/5 - (3 votos)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;\u00bfCu\u00e1ntos dientes tenemos?&quot;,&quot;width&quot;:&quot;75.8&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 75.8px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            2.7\/5 - (3 votos)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seguro que alguna vez te lo has planteado: \u00bftenemos el  [&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":7973,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-7965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ortodoncia-faqs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u25b7 Cuantas piezas dentales tenemos | Ortodoncia Tres Torres<\/title>\n<meta name=\"description\" content=\"No se trata de una cifra, es importante conocer con qu\u00e9 piezas contamos, para entender de d\u00f3nde provienen los problemas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ortodonciabarcelona.com\/blog\/wp-json\/wp\/v2\/posts\/7965\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7 Cuantas piezas dentales tenemos | Ortodoncia Tres Torres\" \/>\n<meta property=\"og:description\" content=\"No se trata de una cifra, es importante conocer con qu\u00e9 piezas contamos, para entender de d\u00f3nde provienen los problemas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ortodonciabarcelona.com\/blog\/wp-json\/wp\/v2\/posts\/7965\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Ortodoncia Tres Torres\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-29T13:48:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-07T13:49:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/familia-sonriente.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dr Fernando de la Iglesia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/cuantos-dientes-tenemos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/cuantos-dientes-tenemos\\\/\"},\"author\":{\"name\":\"Dr Fernando de la Iglesia\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/#\\\/schema\\\/person\\\/694dce2a6f2539dbf05376fb43582751\"},\"headline\":\"\u00bfCu\u00e1ntos dientes tenemos?\",\"datePublished\":\"2025-10-29T13:48:00+00:00\",\"dateModified\":\"2025-11-07T13:49:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/cuantos-dientes-tenemos\\\/\"},\"wordCount\":1114,\"publisher\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/cuantos-dientes-tenemos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/familia-sonriente.jpg\",\"articleSection\":[\"ORTODONCIA FAQS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/cuantos-dientes-tenemos\\\/\",\"url\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/cuantos-dientes-tenemos\\\/\",\"name\":\"\u25b7 Cuantas piezas dentales tenemos | Ortodoncia Tres Torres\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/cuantos-dientes-tenemos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/cuantos-dientes-tenemos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/familia-sonriente.jpg\",\"datePublished\":\"2025-10-29T13:48:00+00:00\",\"dateModified\":\"2025-11-07T13:49:23+00:00\",\"description\":\"No se trata de una cifra, es importante conocer con qu\u00e9 piezas contamos, para entender de d\u00f3nde provienen los problemas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/cuantos-dientes-tenemos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/cuantos-dientes-tenemos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/cuantos-dientes-tenemos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/familia-sonriente.jpg\",\"contentUrl\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/familia-sonriente.jpg\",\"width\":775,\"height\":506,\"caption\":\"Imagen familia sonriente para introducir post \\\"\u00bfCu\u00e1ntos dientes tenemos?\\\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/cuantos-dientes-tenemos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/element_category\\\/columns\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1ntos dientes tenemos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/\",\"name\":\"Blog de Ortodoncia Tres Torres\",\"description\":\"Blog sobre ortodoncia\",\"publisher\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/#organization\",\"name\":\"Blog de Ortodoncia Tres Torres\",\"url\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logotipo-sonrisas_blog-corp.png\",\"contentUrl\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logotipo-sonrisas_blog-corp.png\",\"width\":237,\"height\":283,\"caption\":\"Blog de Ortodoncia Tres Torres\"},\"image\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/#\\\/schema\\\/person\\\/694dce2a6f2539dbf05376fb43582751\",\"name\":\"Dr Fernando de la Iglesia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f556ae41fc83133c68363d54ff867b2e07ec9c9632768f5aa68fda5a3ea4abe8?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f556ae41fc83133c68363d54ff867b2e07ec9c9632768f5aa68fda5a3ea4abe8?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f556ae41fc83133c68363d54ff867b2e07ec9c9632768f5aa68fda5a3ea4abe8?s=96&d=blank&r=g\",\"caption\":\"Dr Fernando de la Iglesia\"},\"description\":\"Licenciado en Odontolog\u00eda por la Universidad de Barcelona. M\u00e1ster y Doctor en Ortodoncia por la Universidad Internacional de Catalu\u00f1a. Miembro de la Sociedad Espa\u00f1ola de Ortodoncia (SEDO).\",\"sameAs\":[\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog\\\/dr-fernando-de-la-iglesia\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7 Cuantas piezas dentales tenemos | Ortodoncia Tres Torres","description":"No se trata de una cifra, es importante conocer con qu\u00e9 piezas contamos, para entender de d\u00f3nde provienen los problemas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ortodonciabarcelona.com\/blog\/wp-json\/wp\/v2\/posts\/7965","og_locale":"es_ES","og_type":"article","og_title":"\u25b7 Cuantas piezas dentales tenemos | Ortodoncia Tres Torres","og_description":"No se trata de una cifra, es importante conocer con qu\u00e9 piezas contamos, para entender de d\u00f3nde provienen los problemas.","og_url":"https:\/\/ortodonciabarcelona.com\/blog\/wp-json\/wp\/v2\/posts\/7965","og_site_name":"Blog de Ortodoncia Tres Torres","article_published_time":"2025-10-29T13:48:00+00:00","article_modified_time":"2025-11-07T13:49:23+00:00","og_image":[{"width":775,"height":506,"url":"https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/familia-sonriente.jpg","type":"image\/jpeg"}],"author":"Dr Fernando de la Iglesia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ortodonciabarcelona.com\/blog\/cuantos-dientes-tenemos\/#article","isPartOf":{"@id":"https:\/\/ortodonciabarcelona.com\/blog\/cuantos-dientes-tenemos\/"},"author":{"name":"Dr Fernando de la Iglesia","@id":"https:\/\/ortodonciabarcelona.com\/blog\/#\/schema\/person\/694dce2a6f2539dbf05376fb43582751"},"headline":"\u00bfCu\u00e1ntos dientes tenemos?","datePublished":"2025-10-29T13:48:00+00:00","dateModified":"2025-11-07T13:49:23+00:00","mainEntityOfPage":{"@id":"https:\/\/ortodonciabarcelona.com\/blog\/cuantos-dientes-tenemos\/"},"wordCount":1114,"publisher":{"@id":"https:\/\/ortodonciabarcelona.com\/blog\/#organization"},"image":{"@id":"https:\/\/ortodonciabarcelona.com\/blog\/cuantos-dientes-tenemos\/#primaryimage"},"thumbnailUrl":"https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/familia-sonriente.jpg","articleSection":["ORTODONCIA FAQS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ortodonciabarcelona.com\/blog\/cuantos-dientes-tenemos\/","url":"https:\/\/ortodonciabarcelona.com\/blog\/cuantos-dientes-tenemos\/","name":"\u25b7 Cuantas piezas dentales tenemos | Ortodoncia Tres Torres","isPartOf":{"@id":"https:\/\/ortodonciabarcelona.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ortodonciabarcelona.com\/blog\/cuantos-dientes-tenemos\/#primaryimage"},"image":{"@id":"https:\/\/ortodonciabarcelona.com\/blog\/cuantos-dientes-tenemos\/#primaryimage"},"thumbnailUrl":"https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/familia-sonriente.jpg","datePublished":"2025-10-29T13:48:00+00:00","dateModified":"2025-11-07T13:49:23+00:00","description":"No se trata de una cifra, es importante conocer con qu\u00e9 piezas contamos, para entender de d\u00f3nde provienen los problemas.","breadcrumb":{"@id":"https:\/\/ortodonciabarcelona.com\/blog\/cuantos-dientes-tenemos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ortodonciabarcelona.com\/blog\/cuantos-dientes-tenemos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ortodonciabarcelona.com\/blog\/cuantos-dientes-tenemos\/#primaryimage","url":"https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/familia-sonriente.jpg","contentUrl":"https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2022\/03\/familia-sonriente.jpg","width":775,"height":506,"caption":"Imagen familia sonriente para introducir post \"\u00bfCu\u00e1ntos dientes tenemos?\""},{"@type":"BreadcrumbList","@id":"https:\/\/ortodonciabarcelona.com\/blog\/cuantos-dientes-tenemos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ortodonciabarcelona.com\/blog\/element_category\/columns\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1ntos dientes tenemos?"}]},{"@type":"WebSite","@id":"https:\/\/ortodonciabarcelona.com\/blog\/#website","url":"https:\/\/ortodonciabarcelona.com\/blog\/","name":"Blog de Ortodoncia Tres Torres","description":"Blog sobre ortodoncia","publisher":{"@id":"https:\/\/ortodonciabarcelona.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ortodonciabarcelona.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ortodonciabarcelona.com\/blog\/#organization","name":"Blog de Ortodoncia Tres Torres","url":"https:\/\/ortodonciabarcelona.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ortodonciabarcelona.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2023\/04\/logotipo-sonrisas_blog-corp.png","contentUrl":"https:\/\/ortodonciabarcelona.com\/blog\/wp-content\/uploads\/2023\/04\/logotipo-sonrisas_blog-corp.png","width":237,"height":283,"caption":"Blog de Ortodoncia Tres Torres"},"image":{"@id":"https:\/\/ortodonciabarcelona.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ortodonciabarcelona.com\/blog\/#\/schema\/person\/694dce2a6f2539dbf05376fb43582751","name":"Dr Fernando de la Iglesia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f556ae41fc83133c68363d54ff867b2e07ec9c9632768f5aa68fda5a3ea4abe8?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f556ae41fc83133c68363d54ff867b2e07ec9c9632768f5aa68fda5a3ea4abe8?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f556ae41fc83133c68363d54ff867b2e07ec9c9632768f5aa68fda5a3ea4abe8?s=96&d=blank&r=g","caption":"Dr Fernando de la Iglesia"},"description":"Licenciado en Odontolog\u00eda por la Universidad de Barcelona. M\u00e1ster y Doctor en Ortodoncia por la Universidad Internacional de Catalu\u00f1a. Miembro de la Sociedad Espa\u00f1ola de Ortodoncia (SEDO).","sameAs":["https:\/\/ortodonciabarcelona.com\/blog\/dr-fernando-de-la-iglesia\/"]}]}},"_links":{"self":[{"href":"https:\/\/ortodonciabarcelona.com\/blog\/wp-json\/wp\/v2\/posts\/7965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ortodonciabarcelona.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ortodonciabarcelona.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ortodonciabarcelona.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ortodonciabarcelona.com\/blog\/wp-json\/wp\/v2\/comments?post=7965"}],"version-history":[{"count":11,"href":"https:\/\/ortodonciabarcelona.com\/blog\/wp-json\/wp\/v2\/posts\/7965\/revisions"}],"predecessor-version":[{"id":8794,"href":"https:\/\/ortodonciabarcelona.com\/blog\/wp-json\/wp\/v2\/posts\/7965\/revisions\/8794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ortodonciabarcelona.com\/blog\/wp-json\/wp\/v2\/media\/7973"}],"wp:attachment":[{"href":"https:\/\/ortodonciabarcelona.com\/blog\/wp-json\/wp\/v2\/media?parent=7965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ortodonciabarcelona.com\/blog\/wp-json\/wp\/v2\/categories?post=7965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ortodonciabarcelona.com\/blog\/wp-json\/wp\/v2\/tags?post=7965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}