{"id":967,"date":"2018-03-06T14:34:51","date_gmt":"2018-03-06T14:34:51","guid":{"rendered":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/?p=967"},"modified":"2023-06-01T08:16:24","modified_gmt":"2023-06-01T08:16:24","slug":"primer-congreso-de-microtornillos-malaga-febrero-2018","status":"publish","type":"post","link":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/primer-congreso-de-microtornillos-malaga-febrero-2018\/","title":{"rendered":"Primer congreso de Microtornillos (M\u00e1laga, Febrero 2018)"},"content":{"rendered":"<p>Los pasados d\u00edas 9 y 10 marzo, el Dr.Fernando de la Iglesia,\u00a0particip\u00f3 en el <strong>1er Congreso de Microtronillos en M\u00e1laga<\/strong>\u00a0 e imparti\u00f3 una conferencia sobre \u201c<strong>Microtornillos y cirug\u00eda ortogn\u00e1tica<\/strong>\u201d y &#8221; <strong>Utilizaci\u00f3n de Microtornillos en dientes incluidos<\/strong>&#8220;, hablando sobre las diferentes opciones para poder emplear microtornillos en casos de cirug\u00eda bimaxilar con &#8220;Surgery First&#8221; con segmentaci\u00f3n del maxilar. Asimismo, explic\u00f3 el protocolo utilizado en Ortodoncia Tres Torres para tratar los dientes incluidos, haciendo especial hincapi\u00e9 en tracci\u00f3n de los caninos incluidos con los microtornillos <a href=\"http:\/\/microdentsystem.com\/videoteca\/ortodoncia\" target=\"_blank\" rel=\"nofollow noopener\">Microdent,<\/a> que tienen un cabezal capaz de poder ligar un arco y as\u00ed realizar la tracci\u00f3n.<\/p>\n<p><img decoding=\"async\" class=\"lazyload alignnone wp-image-1498 size-full\" src=\"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2022\/10\/Dr-Fernando-de-la-Iglesia-Ortodoncia-Tres-Torres-barcelona.jpg\" data-orig-src=\"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2022\/10\/Dr-Fernando-de-la-Iglesia-Ortodoncia-Tres-Torres-barcelona.jpg\" alt=\"Foto 2: El Dr.Fernando de la Iglesia particip\u00f3 en el Primer Congreso de Microtronillos en M\u00e1laga\" width=\"2100\" height=\"1400\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272100%27%20height%3D%271400%27%20viewBox%3D%270%200%202100%201400%27%3E%3Crect%20width%3D%272100%27%20height%3D%271400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2022\/10\/Dr-Fernando-de-la-Iglesia-Ortodoncia-Tres-Torres-barcelona-200x133.jpg 200w, https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2022\/10\/Dr-Fernando-de-la-Iglesia-Ortodoncia-Tres-Torres-barcelona-300x200.jpg 300w, https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2022\/10\/Dr-Fernando-de-la-Iglesia-Ortodoncia-Tres-Torres-barcelona-400x267.jpg 400w, https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2022\/10\/Dr-Fernando-de-la-Iglesia-Ortodoncia-Tres-Torres-barcelona-600x400.jpg 600w, https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2022\/10\/Dr-Fernando-de-la-Iglesia-Ortodoncia-Tres-Torres-barcelona-768x512.jpg 768w, https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2022\/10\/Dr-Fernando-de-la-Iglesia-Ortodoncia-Tres-Torres-barcelona-800x533.jpg 800w, https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2022\/10\/Dr-Fernando-de-la-Iglesia-Ortodoncia-Tres-Torres-barcelona-1024x683.jpg 1024w, https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2022\/10\/Dr-Fernando-de-la-Iglesia-Ortodoncia-Tres-Torres-barcelona-1200x800.jpg 1200w, https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2022\/10\/Dr-Fernando-de-la-Iglesia-Ortodoncia-Tres-Torres-barcelona-1536x1024.jpg 1536w, https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2022\/10\/Dr-Fernando-de-la-Iglesia-Ortodoncia-Tres-Torres-barcelona.jpg 2100w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 2100px) 100vw, 2100px\" \/><\/p>\n<div id=\"attachment_968\" style=\"width: 3898px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-968\" class=\"lazyload size-full wp-image-968\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%273888%27%20height%3D%272592%27%20viewBox%3D%270%200%203888%202592%27%3E%3Crect%20width%3D%273888%27%20height%3D%272592%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2018\/02\/Dr-Fernando-de-la-Iglesia-Ortodoncia-barcelona.jpg\" alt=\"Foto 1: Doctor de la Iglesia durante su conferencia\" width=\"3888\" height=\"2592\" \/><p id=\"caption-attachment-968\" class=\"wp-caption-text\">Foto 2: Doctor de la Iglesia durante su conferencia<\/p><\/div>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;967&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Punt\u00faa este post&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Primer congreso de Microtornillos (M\u00e1laga, Febrero 2018)&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">Punt\u00faa este post<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los pasados d\u00edas 9 y 10 marzo, el Dr.Fernando de  [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":970,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Primer congreso de Microtornillos en M\u00e1laga<\/title>\n<meta name=\"description\" content=\"El Dr. Fernando de la Iglesia particip\u00f3 en el Primer Congreso de Microtronillos en M\u00e1laga, en nuestro blog profesional informaci\u00f3n sobre su conferencia\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primer congreso de Microtornillos en M\u00e1laga\" \/>\n<meta property=\"og:description\" content=\"El Dr. Fernando de la Iglesia particip\u00f3 en el Primer Congreso de Microtronillos en M\u00e1laga, en nuestro blog profesional informaci\u00f3n sobre su conferencia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ortodonciabarcelona.com\/blog-profesional\/primer-congreso-de-microtornillos-malaga-febrero-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Profesional Ortodoncia Tres Torres\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-06T14:34:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-01T08:16:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2018\/02\/microtornillos-curso-fernando-de-la-iglesia-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1829\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dr. Fernando de la Iglesia Beyme\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dr. Fernando de la Iglesia Beyme\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/primer-congreso-de-microtornillos-malaga-febrero-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/primer-congreso-de-microtornillos-malaga-febrero-2018\\\/\"},\"author\":{\"name\":\"Dr. Fernando de la Iglesia Beyme\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/#\\\/schema\\\/person\\\/6e8f1e4d584209c52f7c939dd0752f33\"},\"headline\":\"Primer congreso de Microtornillos (M\u00e1laga, Febrero 2018)\",\"datePublished\":\"2018-03-06T14:34:51+00:00\",\"dateModified\":\"2023-06-01T08:16:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/primer-congreso-de-microtornillos-malaga-febrero-2018\\\/\"},\"wordCount\":130,\"publisher\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/primer-congreso-de-microtornillos-malaga-febrero-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/microtornillos-curso-fernando-de-la-iglesia-scaled.jpg\",\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/primer-congreso-de-microtornillos-malaga-febrero-2018\\\/\",\"url\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/primer-congreso-de-microtornillos-malaga-febrero-2018\\\/\",\"name\":\"Primer congreso de Microtornillos en M\u00e1laga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/primer-congreso-de-microtornillos-malaga-febrero-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/primer-congreso-de-microtornillos-malaga-febrero-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/microtornillos-curso-fernando-de-la-iglesia-scaled.jpg\",\"datePublished\":\"2018-03-06T14:34:51+00:00\",\"dateModified\":\"2023-06-01T08:16:24+00:00\",\"description\":\"El Dr. Fernando de la Iglesia particip\u00f3 en el Primer Congreso de Microtronillos en M\u00e1laga, en nuestro blog profesional informaci\u00f3n sobre su conferencia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/primer-congreso-de-microtornillos-malaga-febrero-2018\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/primer-congreso-de-microtornillos-malaga-febrero-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/primer-congreso-de-microtornillos-malaga-febrero-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/microtornillos-curso-fernando-de-la-iglesia-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/microtornillos-curso-fernando-de-la-iglesia-scaled.jpg\",\"width\":1829,\"height\":2560,\"caption\":\"Foto 1: El Dr.Fernando de la Iglesia particip\u00f3 en el Primer Congreso de Microtronillos en M\u00e1laga\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/primer-congreso-de-microtornillos-malaga-febrero-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primer congreso de Microtornillos (M\u00e1laga, Febrero 2018)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/#website\",\"url\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/\",\"name\":\"Blog Profesional Ortodoncia Tres Torres\",\"description\":\"Blog profesional sobre ortodoncia\",\"publisher\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/#organization\",\"name\":\"Blog Profesional Ortodoncia Tres Torres\",\"url\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo-blog-profesional-vertical.png\",\"contentUrl\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo-blog-profesional-vertical.png\",\"width\":253,\"height\":323,\"caption\":\"Blog Profesional Ortodoncia Tres Torres\"},\"image\":{\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/#\\\/schema\\\/person\\\/6e8f1e4d584209c52f7c939dd0752f33\",\"name\":\"Dr. Fernando de la Iglesia Beyme\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f556ae41fc83133c68363d54ff867b2e07ec9c9632768f5aa68fda5a3ea4abe8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f556ae41fc83133c68363d54ff867b2e07ec9c9632768f5aa68fda5a3ea4abe8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f556ae41fc83133c68363d54ff867b2e07ec9c9632768f5aa68fda5a3ea4abe8?s=96&d=mm&r=g\",\"caption\":\"Dr. Fernando de la Iglesia Beyme\"},\"description\":\"Licenciado en Odontolog\u00eda por la Universidad de Barcelona. M\u00e1ster y Doctor en Ortodoncia por la Universidad Internacional de Catalu\u00f1a. Miembro de la Sociedad Espa\u00f1ola de Ortodoncia (SEDO).\",\"sameAs\":[\"https:\\\/\\\/ortodonciabarcelona.com\\\/blog-profesional\\\/dr-fernando-de-la-iglesia\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primer congreso de Microtornillos en M\u00e1laga","description":"El Dr. Fernando de la Iglesia particip\u00f3 en el Primer Congreso de Microtronillos en M\u00e1laga, en nuestro blog profesional informaci\u00f3n sobre su conferencia","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Primer congreso de Microtornillos en M\u00e1laga","og_description":"El Dr. Fernando de la Iglesia particip\u00f3 en el Primer Congreso de Microtronillos en M\u00e1laga, en nuestro blog profesional informaci\u00f3n sobre su conferencia","og_url":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/primer-congreso-de-microtornillos-malaga-febrero-2018\/","og_site_name":"Blog Profesional Ortodoncia Tres Torres","article_published_time":"2018-03-06T14:34:51+00:00","article_modified_time":"2023-06-01T08:16:24+00:00","og_image":[{"width":1829,"height":2560,"url":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2018\/02\/microtornillos-curso-fernando-de-la-iglesia-scaled.jpg","type":"image\/jpeg"}],"author":"Dr. Fernando de la Iglesia Beyme","twitter_misc":{"Escrito por":"Dr. Fernando de la Iglesia Beyme","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/primer-congreso-de-microtornillos-malaga-febrero-2018\/#article","isPartOf":{"@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/primer-congreso-de-microtornillos-malaga-febrero-2018\/"},"author":{"name":"Dr. Fernando de la Iglesia Beyme","@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/#\/schema\/person\/6e8f1e4d584209c52f7c939dd0752f33"},"headline":"Primer congreso de Microtornillos (M\u00e1laga, Febrero 2018)","datePublished":"2018-03-06T14:34:51+00:00","dateModified":"2023-06-01T08:16:24+00:00","mainEntityOfPage":{"@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/primer-congreso-de-microtornillos-malaga-febrero-2018\/"},"wordCount":130,"publisher":{"@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/#organization"},"image":{"@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/primer-congreso-de-microtornillos-malaga-febrero-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2018\/02\/microtornillos-curso-fernando-de-la-iglesia-scaled.jpg","articleSection":["noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/primer-congreso-de-microtornillos-malaga-febrero-2018\/","url":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/primer-congreso-de-microtornillos-malaga-febrero-2018\/","name":"Primer congreso de Microtornillos en M\u00e1laga","isPartOf":{"@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/primer-congreso-de-microtornillos-malaga-febrero-2018\/#primaryimage"},"image":{"@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/primer-congreso-de-microtornillos-malaga-febrero-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2018\/02\/microtornillos-curso-fernando-de-la-iglesia-scaled.jpg","datePublished":"2018-03-06T14:34:51+00:00","dateModified":"2023-06-01T08:16:24+00:00","description":"El Dr. Fernando de la Iglesia particip\u00f3 en el Primer Congreso de Microtronillos en M\u00e1laga, en nuestro blog profesional informaci\u00f3n sobre su conferencia","breadcrumb":{"@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/primer-congreso-de-microtornillos-malaga-febrero-2018\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ortodonciabarcelona.com\/blog-profesional\/primer-congreso-de-microtornillos-malaga-febrero-2018\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/primer-congreso-de-microtornillos-malaga-febrero-2018\/#primaryimage","url":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2018\/02\/microtornillos-curso-fernando-de-la-iglesia-scaled.jpg","contentUrl":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2018\/02\/microtornillos-curso-fernando-de-la-iglesia-scaled.jpg","width":1829,"height":2560,"caption":"Foto 1: El Dr.Fernando de la Iglesia particip\u00f3 en el Primer Congreso de Microtronillos en M\u00e1laga"},{"@type":"BreadcrumbList","@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/primer-congreso-de-microtornillos-malaga-febrero-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/"},{"@type":"ListItem","position":2,"name":"Primer congreso de Microtornillos (M\u00e1laga, Febrero 2018)"}]},{"@type":"WebSite","@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/#website","url":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/","name":"Blog Profesional Ortodoncia Tres Torres","description":"Blog profesional sobre ortodoncia","publisher":{"@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/#organization","name":"Blog Profesional Ortodoncia Tres Torres","url":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/#\/schema\/logo\/image\/","url":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2023\/05\/logo-blog-profesional-vertical.png","contentUrl":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-content\/uploads\/2023\/05\/logo-blog-profesional-vertical.png","width":253,"height":323,"caption":"Blog Profesional Ortodoncia Tres Torres"},"image":{"@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/#\/schema\/person\/6e8f1e4d584209c52f7c939dd0752f33","name":"Dr. Fernando de la Iglesia Beyme","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f556ae41fc83133c68363d54ff867b2e07ec9c9632768f5aa68fda5a3ea4abe8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f556ae41fc83133c68363d54ff867b2e07ec9c9632768f5aa68fda5a3ea4abe8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f556ae41fc83133c68363d54ff867b2e07ec9c9632768f5aa68fda5a3ea4abe8?s=96&d=mm&r=g","caption":"Dr. Fernando de la Iglesia Beyme"},"description":"Licenciado en Odontolog\u00eda por la Universidad de Barcelona. M\u00e1ster y Doctor en Ortodoncia por la Universidad Internacional de Catalu\u00f1a. Miembro de la Sociedad Espa\u00f1ola de Ortodoncia (SEDO).","sameAs":["https:\/\/ortodonciabarcelona.com\/blog-profesional\/dr-fernando-de-la-iglesia\/"]}]}},"_links":{"self":[{"href":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-json\/wp\/v2\/posts\/967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-json\/wp\/v2\/comments?post=967"}],"version-history":[{"count":7,"href":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-json\/wp\/v2\/posts\/967\/revisions"}],"predecessor-version":[{"id":1499,"href":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-json\/wp\/v2\/posts\/967\/revisions\/1499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-json\/wp\/v2\/media\/970"}],"wp:attachment":[{"href":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-json\/wp\/v2\/media?parent=967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-json\/wp\/v2\/categories?post=967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ortodonciabarcelona.com\/blog-profesional\/wp-json\/wp\/v2\/tags?post=967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}